{"id":25672,"date":"2023-12-18T10:43:38","date_gmt":"2023-12-18T09:43:38","guid":{"rendered":"https:\/\/www.catedraemalcsa.com\/?p=25672"},"modified":"2025-07-30T15:07:00","modified_gmt":"2025-07-30T13:07:00","slug":"o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos","status":"publish","type":"post","link":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/","title":{"rendered":"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos"},"content":{"rendered":"\n<p><strong>La innovaci\u00f3n forma parte del ADN de Emalcsa.<\/strong> De hecho la Empresa Municipal de Aguas de A Coru\u00f1a lleva impulsando iniciativas innovadoras pr\u00e1cticamente desde su fundaci\u00f3n, all\u00e1 por el a\u00f1o 1908, cuando todav\u00eda se denominaba Aguas de La Coru\u00f1a S. A. Valga como ejemplo la <strong>instalaci\u00f3n de filtros lentos en la primitiva planta de Ca\u00f1\u00e1s (Carral) en 1915, lo que supuso entonces un importante avance en el abastecimiento de agua a la poblaci\u00f3n de A Coru\u00f1a y un relevante hecho hist\u00f3rico.<\/strong> De hecho, A Coru\u00f1a era la segunda ciudad de Espa\u00f1a en la que se utilizaban estos filtros. La ETAP de Ca\u00f1\u00e1s, por cierto, sigue operativa. S\u00f3lo abastece a Carral, pero es la estaci\u00f3n de tratamiento de agua potable m\u00e1s antigua de Espa\u00f1a en funcionamiento y un enclave fundamental del patrimonio de Emalcsa, siempre pendiente de su mantenimiento y conservaci\u00f3n.<\/p>\n\n<p>En 2013, no obstante, la direcci\u00f3n de la empresa decidi\u00f3 potenciar los recursos destinados a la innovaci\u00f3n de la compa\u00f1\u00eda y puso en marcha el \u00e1rea de I+D+i, hoy integrada en la C\u00e1tedra Emalcsa-UDC. Desde entonces se han desarrollado 29 proyectos de diferente naturaleza de 45 planteados. El primero, el AquaPlann Project, que se inici\u00f3 en 2010 y finaliz\u00f3 en 2013, a\u00f1o en el que naci\u00f3 el departamento de innovaci\u00f3n. Este 2023 que est\u00e1 a punto de concluir se cumplen, por lo tanto, diez a\u00f1os de la finalizaci\u00f3n de aquel proyecto.<\/p>\n\n<p>El AquaPlann Project cont\u00f3 con la financiaci\u00f3n de la Comisi\u00f3n Europea a trav\u00e9s del programa LIFE+. Su presupuesto total fue de 987.564 euros, 98.756,40 de los cuales fueron aportados por Emalcsa. El objetivo de esta iniciativa, en la que tambi\u00e9n <strong>participaron el <a href=\"http:\/\/www.abegondo.es\/\">Concello de Abegondo<\/a>, la <a href=\"https:\/\/augasdegalicia.xunta.gal\/\">Conseller\u00eda de Medio Ambiente, Territorio e Infraestructuras-Augas de Galicia<\/a> y la <a href=\"https:\/\/mediorural.xunta.gal\/gl\">Conseller\u00eda de Medio Rural y del Mar<\/a>,<\/strong> era <strong>asegurar el buen estado ecol\u00f3gico de las aguas del embalse de Cecebre y de la cuenca hidrogr\u00e1fica de los r\u00edos Mero y Barc\u00e9s. Asimismo tambi\u00e9n se persegu\u00eda el fomento de buenas pr\u00e1cticas en el uso del agua por parte de los habitantes del territorio. De este modo se conseguir\u00eda situar la zona de actuaci\u00f3n en la vanguardia europea en lo que respecta a la aplicaci\u00f3n de la Directiva Marco del Agua.<\/strong><\/p>\n\n<p><\/p>\n\n<h3 class=\"wp-block-heading\">Trabajos desarrollados por Emalcsa<\/h3>\n\n<p><strong>Las competencias de Emalcsa en este proyecto fueron analizar el riesgo de contaminaci\u00f3n de la cuenca y el dise\u00f1o de un plan de contingencia; realizar un estudio de la calidad de las aguas y del grado de eutrofizaci\u00f3n del embalse (cuando las aguas se quedan sin ox\u00edgeno y registran un alto n\u00famero de nutrientes); desarrollar campa\u00f1as de sensibilizaci\u00f3n en el \u00e1rea de A Coru\u00f1a; y, finalmente, organizar jornadas sobre el agua, que tuvieron lugar en la Casa del Agua el 28 y 29 de octubre de 2010 y el 3 y el 4 de noviembre de 2011.<\/strong><\/p>\n\n<p><strong>El AquaPlann <a href=\"https:\/\/gestoresderesiduos.org\/noticias\/galicia-gana-con-los-premios-medio-ambiente-aproema-2012\">recibi\u00f3 en 2012 el Premio Medio Ambiente que concede la Asociaci\u00f3n Profesional de Empresas Medioambientales de Galicia (APROEMA)<\/a>. Adem\u00e1s, tambi\u00e9n <a href=\"http:\/\/www.premioconama.org\/premios12\/paginas\/paginas_view.php?lang=es&amp;buscar=abegondo&amp;idfiltro=0&amp;idpagina\">en 2012, consigui\u00f3 un acc\u00e9sit en el Premio a la Sostenibilidad de Peque\u00f1os y Medianos Municipios que concede cada a\u00f1o el Congreso Nacional de Medio Ambiente<\/a>.<\/strong> El Aqua Plann acab\u00f3 en segunda posici\u00f3n, entre 31 proyectos presentados.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2025\/07\/triptico-aquaplann_Pagina_3-1024x724.png\" alt=\"\" class=\"wp-image-25675\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La innovaci\u00f3n forma parte del ADN de Emalcsa. De hecho la Empresa Municipal de Aguas de A Coru\u00f1a lleva impulsando iniciativas innovadoras pr\u00e1cticamente desde su fundaci\u00f3n, all\u00e1 por el a\u00f1o 1908, cuando todav\u00eda se denominaba Aguas de La Coru\u00f1a S. A. Valga como ejemplo la instalaci\u00f3n de filtros lentos en la primitiva planta de Ca\u00f1\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25673,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[368],"tags":[20,169,31,49,67],"class_list":["post-25672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidade","tag-a-coruna-2","tag-area-de-idi","tag-catedra-emalcsa-udc-2","tag-cecebre-2","tag-emalcsa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos - C\u00e1tedra Emalcsa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos - C\u00e1tedra Emalcsa\" \/>\n<meta property=\"og:description\" content=\"La innovaci\u00f3n forma parte del ADN de Emalcsa. De hecho la Empresa Municipal de Aguas de A Coru\u00f1a lleva impulsando iniciativas innovadoras pr\u00e1cticamente desde su fundaci\u00f3n, all\u00e1 por el a\u00f1o 1908, cuando todav\u00eda se denominaba Aguas de La Coru\u00f1a S. A. Valga como ejemplo la instalaci\u00f3n de filtros lentos en la primitiva planta de Ca\u00f1\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00e1tedra Emalcsa\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-18T09:43:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T13:07:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2023\/04\/Mesa-de-trabajo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"949\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"emalcsawp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"emalcsawp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/\"},\"author\":{\"name\":\"emalcsawp\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#\\\/schema\\\/person\\\/efb560fa9370bb4ce0760f6ef7a53907\"},\"headline\":\"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos\",\"datePublished\":\"2023-12-18T09:43:38+00:00\",\"dateModified\":\"2025-07-30T13:07:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/\"},\"wordCount\":599,\"publisher\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/encoro-de-abegondo-cecebre-abegondo_img4812n1t0.jpg\",\"keywords\":[\"A Coru\u00f1a\",\"\u00e1rea de I+D+i\",\"C\u00e1tedra Emalcsa-UDC\",\"Cecebre\",\"Emalcsa\"],\"articleSection\":[\"Actualidade\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/\",\"url\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/\",\"name\":\"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos - C\u00e1tedra Emalcsa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/encoro-de-abegondo-cecebre-abegondo_img4812n1t0.jpg\",\"datePublished\":\"2023-12-18T09:43:38+00:00\",\"dateModified\":\"2025-07-30T13:07:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/encoro-de-abegondo-cecebre-abegondo_img4812n1t0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/encoro-de-abegondo-cecebre-abegondo_img4812n1t0.jpg\",\"width\":1024,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/\",\"name\":\"C\u00e1tedra Emalcsa\",\"description\":\"C\u00e1tedra EMALCSA-UDC promover y articular la investigaci\u00f3n, innovaci\u00f3n y transferencia de conocimiento en el \u00e1mbito los sistemas de agua.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#organization\",\"name\":\"C\u00e1tedra Emalcsa\",\"url\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Catedra-Emalcsa-UDC.svg\",\"contentUrl\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Catedra-Emalcsa-UDC.svg\",\"width\":185,\"height\":58,\"caption\":\"C\u00e1tedra Emalcsa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/#\\\/schema\\\/person\\\/efb560fa9370bb4ce0760f6ef7a53907\",\"name\":\"emalcsawp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80db74ffb4beb0be788543a1f45b29875710fd2c515220ced2e80bde3709de50?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80db74ffb4beb0be788543a1f45b29875710fd2c515220ced2e80bde3709de50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80db74ffb4beb0be788543a1f45b29875710fd2c515220ced2e80bde3709de50?s=96&d=mm&r=g\",\"caption\":\"emalcsawp\"},\"sameAs\":[\"https:\\\/\\\/www.catedraemalcsa.com\"],\"url\":\"https:\\\/\\\/www.catedraemalcsa.com\\\/gl\\\/author\\\/emalcsawp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos - C\u00e1tedra Emalcsa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/","og_locale":"gl_ES","og_type":"article","og_title":"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos - C\u00e1tedra Emalcsa","og_description":"La innovaci\u00f3n forma parte del ADN de Emalcsa. De hecho la Empresa Municipal de Aguas de A Coru\u00f1a lleva impulsando iniciativas innovadoras pr\u00e1cticamente desde su fundaci\u00f3n, all\u00e1 por el a\u00f1o 1908, cuando todav\u00eda se denominaba Aguas de La Coru\u00f1a S. A. Valga como ejemplo la instalaci\u00f3n de filtros lentos en la primitiva planta de Ca\u00f1\u00e1s [&hellip;]","og_url":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/","og_site_name":"C\u00e1tedra Emalcsa","article_published_time":"2023-12-18T09:43:38+00:00","article_modified_time":"2025-07-30T13:07:00+00:00","og_image":[{"width":1500,"height":949,"url":"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2023\/04\/Mesa-de-trabajo-1.png","type":"image\/png"}],"author":"emalcsawp","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"emalcsawp","Tempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/#article","isPartOf":{"@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/"},"author":{"name":"emalcsawp","@id":"https:\/\/www.catedraemalcsa.com\/#\/schema\/person\/efb560fa9370bb4ce0760f6ef7a53907"},"headline":"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos","datePublished":"2023-12-18T09:43:38+00:00","dateModified":"2025-07-30T13:07:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/"},"wordCount":599,"publisher":{"@id":"https:\/\/www.catedraemalcsa.com\/#organization"},"image":{"@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2023\/12\/encoro-de-abegondo-cecebre-abegondo_img4812n1t0.jpg","keywords":["A Coru\u00f1a","\u00e1rea de I+D+i","C\u00e1tedra Emalcsa-UDC","Cecebre","Emalcsa"],"articleSection":["Actualidade"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/","url":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/","name":"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos - C\u00e1tedra Emalcsa","isPartOf":{"@id":"https:\/\/www.catedraemalcsa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2023\/12\/encoro-de-abegondo-cecebre-abegondo_img4812n1t0.jpg","datePublished":"2023-12-18T09:43:38+00:00","dateModified":"2025-07-30T13:07:00+00:00","breadcrumb":{"@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/#primaryimage","url":"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2023\/12\/encoro-de-abegondo-cecebre-abegondo_img4812n1t0.jpg","contentUrl":"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2023\/12\/encoro-de-abegondo-cecebre-abegondo_img4812n1t0.jpg","width":1024,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/www.catedraemalcsa.com\/gl\/o-aquaplann-primeiro-proxecto-do-area-de-idi-de-emalcsa-cuxo-obxectivo-era-asegurar-o-bo-estado-ecoloxico-das-augas-do-encoro-de-cecebre-cumpre-dez-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.catedraemalcsa.com\/"},{"@type":"ListItem","position":2,"name":"O AquaPlann, primeiro proxecto do \u00e1rea de I+D+i de Emalcsa, cuxo obxectivo era asegurar o bo estado ecol\u00f3xico das augas do encoro de Cecebre, cumpre dez anos"}]},{"@type":"WebSite","@id":"https:\/\/www.catedraemalcsa.com\/#website","url":"https:\/\/www.catedraemalcsa.com\/","name":"C\u00e1tedra Emalcsa","description":"C\u00e1tedra EMALCSA-UDC promover y articular la investigaci\u00f3n, innovaci\u00f3n y transferencia de conocimiento en el \u00e1mbito los sistemas de agua.","publisher":{"@id":"https:\/\/www.catedraemalcsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.catedraemalcsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.catedraemalcsa.com\/#organization","name":"C\u00e1tedra Emalcsa","url":"https:\/\/www.catedraemalcsa.com\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.catedraemalcsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2025\/07\/Catedra-Emalcsa-UDC.svg","contentUrl":"https:\/\/www.catedraemalcsa.com\/wp-content\/uploads\/2025\/07\/Catedra-Emalcsa-UDC.svg","width":185,"height":58,"caption":"C\u00e1tedra Emalcsa"},"image":{"@id":"https:\/\/www.catedraemalcsa.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.catedraemalcsa.com\/#\/schema\/person\/efb560fa9370bb4ce0760f6ef7a53907","name":"emalcsawp","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/80db74ffb4beb0be788543a1f45b29875710fd2c515220ced2e80bde3709de50?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80db74ffb4beb0be788543a1f45b29875710fd2c515220ced2e80bde3709de50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80db74ffb4beb0be788543a1f45b29875710fd2c515220ced2e80bde3709de50?s=96&d=mm&r=g","caption":"emalcsawp"},"sameAs":["https:\/\/www.catedraemalcsa.com"],"url":"https:\/\/www.catedraemalcsa.com\/gl\/author\/emalcsawp\/"}]}},"_links":{"self":[{"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/posts\/25672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/comments?post=25672"}],"version-history":[{"count":3,"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/posts\/25672\/revisions"}],"predecessor-version":[{"id":28439,"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/posts\/25672\/revisions\/28439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/media\/25673"}],"wp:attachment":[{"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/media?parent=25672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/categories?post=25672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedraemalcsa.com\/gl\/wp-json\/wp\/v2\/tags?post=25672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}